{"id":5782,"date":"2025-06-25T21:55:00","date_gmt":"2025-06-26T01:55:00","guid":{"rendered":"https:\/\/hexibella.com\/?post_type=product&#038;p=5782"},"modified":"2025-09-27T19:34:59","modified_gmt":"2025-09-27T23:34:59","slug":"nad","status":"publish","type":"product","link":"https:\/\/hexibella-modehaus.de\/pt\/product\/nad\/","title":{"rendered":"NAD+ Catakor - Foco e energia"},"content":{"rendered":"<div class=\"wp-block-media-text is-stacked-on-mobile has-palette-color-6-color has-black-background-color has-text-color has-background has-link-color wp-elements-1d7892e64a26e65973caa49c20745919\" style=\"border-radius:5px;grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/NAD-Benefits.png\" alt=\"\" class=\"wp-image-6830 size-full\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/NAD-Benefits.png 800w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/NAD-Benefits-300x300.png 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/NAD-Benefits-150x150.png 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/NAD-Benefits-768x768.png 768w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/NAD-Benefits-12x12.png 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/NAD-Benefits-80x80.png 80w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-palette-color-6-color has-text-color has-link-color wp-elements-76f2ac97c568dab213b76ea2c66020b0\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);font-size:clamp(18.959px, 1.185rem + ((1vw - 3.2px) * 0.863), 30px);\">Melhor humor, mais energia e corpo mais jovem<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A NAD+ \u00e9 a principal coenzima respons\u00e1vel pela convers\u00e3o de alimentos em energia. \u00c0 medida que envelhecemos, o NAD+ diminui, o que prejudica o metabolismo celular e a produ\u00e7\u00e3o de prote\u00ednas na pele, no c\u00e9rebro e em todo o corpo. Ao tomar Liposomal NAD+ (absor\u00e7\u00e3o 9 vezes melhor do que o NAD+ comum), voc\u00ea pode restaurar o metabolismo celular e superar a fadiga energ\u00e9tica, aumentando significativamente a quantidade de energia produzida pelas mitoc\u00f4ndrias. Isso o deixa energizado para a vida ap\u00f3s o trabalho, para as noites com amigos e familiares e permite que voc\u00ea diga adeus \u00e0s quedas de energia \u00e0s 15 horas.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider uagb-block-1aa36a3e uagb-slider-container\"><div class=\"uagb-slides uagb-swiper\"><div class=\"swiper-wrapper\">\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-a48db4ab\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-96decfcb alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><style>.kb-image5782_520f62-ee.kb-image-is-ratio-size, .kb-image5782_520f62-ee .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_520f62-ee.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_520f62-ee .kb-image-is-ratio-size{align-self:unset;}.kb-image5782_520f62-ee figure{max-width:280px;}.kb-image5782_520f62-ee .image-is-svg, .kb-image5782_520f62-ee .image-is-svg img{width:100%;}.kb-image5782_520f62-ee .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image5782_520f62-ee img.kb-img, .kb-image5782_520f62-ee .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;object-position:44% 41%;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5782_520f62-ee\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><a href=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/71JOw80WSOL.webp\" class=\"kb-advanced-image-link\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/71JOw80WSOL.webp\" alt=\"\" class=\"kb-img wp-image-6826\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71JOw80WSOL.webp 600w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71JOw80WSOL-300x300.webp 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71JOw80WSOL-150x150.webp 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71JOw80WSOL-12x12.webp 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71JOw80WSOL-80x80.webp 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Estou tomando esse produto h\u00e1 cerca de 4 meses e tive resultados surpreendentes. Vou ao quiropr\u00e1tico toda semana porque tenho uma defici\u00eancia de col\u00e1geno e preciso ser ajustada com frequ\u00eancia. Meu quiropr\u00e1tico diz que estou muito melhor do que antes e tamb\u00e9m me sinto muito bem. Meus n\u00edveis de energia est\u00e3o altos e consigo me concentrar muito melhor agora. Este \u00e9 o melhor suplemento que j\u00e1 tomei!<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Savannah, \u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n\n\n\n<div style=\"height:7px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-fd7c72b0\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-c03f04ea alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><style>.kb-image5782_fdbc23-b6.kb-image-is-ratio-size, .kb-image5782_fdbc23-b6 .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_fdbc23-b6.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_fdbc23-b6 .kb-image-is-ratio-size{align-self:unset;}.kb-image5782_fdbc23-b6 figure{max-width:280px;}.kb-image5782_fdbc23-b6 .image-is-svg, .kb-image5782_fdbc23-b6 .image-is-svg img{width:100%;}.kb-image5782_fdbc23-b6 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image5782_fdbc23-b6 img.kb-img, .kb-image5782_fdbc23-b6 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;object-position:53% 47%;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5782_fdbc23-b6\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><a href=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_.webp\" class=\"kb-advanced-image-link\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_.webp\" alt=\"\" class=\"kb-img wp-image-6825\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_.webp 600w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_-300x300.webp 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_-150x150.webp 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_-12x12.webp 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61ZJwaSeymL._AC_FMavif_UC231231_CACC231231_QL58_-80x80.webp 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Acabei de terminar meu primeiro frasco de 30 dias de Liposomal NAD CORE (250 mg) e estou impressionado. Escolhi esse produto porque queria um suporte suave para o envelhecimento saud\u00e1vel e a energia di\u00e1ria, em vez de uma \"solu\u00e7\u00e3o r\u00e1pida\" que causasse nervosismo, e ele me atendeu.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Jackie, \u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n\n\n\n<div style=\"height:7px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-abb3d096\"><div class=\"swiper-content\">\n<div class=\"wp-block-uagb-container uagb-block-d6939f66 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><style>.kb-image5782_cfc2cc-98.kb-image-is-ratio-size, .kb-image5782_cfc2cc-98 .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_cfc2cc-98.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_cfc2cc-98 .kb-image-is-ratio-size{align-self:unset;}.kb-image5782_cfc2cc-98 figure{max-width:280px;}.kb-image5782_cfc2cc-98 .image-is-svg, .kb-image5782_cfc2cc-98 .image-is-svg img{width:100%;}.kb-image5782_cfc2cc-98 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image5782_cfc2cc-98 img.kb-img, .kb-image5782_cfc2cc-98 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5782_cfc2cc-98\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><a href=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/61BKRKYKosL._AC_FMavif_UC231231_CACC231231_QL58_.jpg\" class=\"kb-advanced-image-link\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img decoding=\"async\" width=\"231\" height=\"231\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/61BKRKYKosL._AC_FMavif_UC231231_CACC231231_QL58_.jpg\" alt=\"\" class=\"kb-img wp-image-6823\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61BKRKYKosL._AC_FMavif_UC231231_CACC231231_QL58_.jpg 231w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61BKRKYKosL._AC_FMavif_UC231231_CACC231231_QL58_-150x150.jpg 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61BKRKYKosL._AC_FMavif_UC231231_CACC231231_QL58_-12x12.jpg 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61BKRKYKosL._AC_FMavif_UC231231_CACC231231_QL58_-80x80.jpg 80w\" sizes=\"(max-width: 231px) 100vw, 231px\" \/><\/div><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Uau! S\u00f3 estou tomando h\u00e1 cerca de um m\u00eas e j\u00e1 me sinto 20 anos mais jovem. Minhas unhas est\u00e3o crescendo, meu cabelo est\u00e1 crescendo e tenho muita energia. Tamb\u00e9m tenho menos dores e inc\u00f4modos!<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Katrina, \u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n\n\n\n<div style=\"height:7px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-8a35d10a\"><div class=\"swiper-content\"><style>.kb-image5782_838718-cd.kb-image-is-ratio-size, .kb-image5782_838718-cd .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_838718-cd.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_838718-cd .kb-image-is-ratio-size{align-self:unset;}.kb-image5782_838718-cd figure{max-width:280px;}.kb-image5782_838718-cd .image-is-svg, .kb-image5782_838718-cd .image-is-svg img{width:100%;}.kb-image5782_838718-cd .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image5782_838718-cd img.kb-img, .kb-image5782_838718-cd .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;object-position:50% 60%;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5782_838718-cd\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><a href=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1.webp\" class=\"kb-advanced-image-link\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1.webp\" alt=\"\" class=\"kb-img wp-image-6824\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1.webp 600w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1-300x300.webp 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1-150x150.webp 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1-12x12.webp 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/61DxSTSEOPL-1-80x80.webp 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30)\">A clareza mental e a resist\u00eancia melhoraram. N\u00e3o \u00e9 um milagre da noite para o dia, mas sem d\u00favida me sinto mais n\u00edtido e mais vivo. A pele tamb\u00e9m est\u00e1 muito radiante.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Alexis, \u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-slider-child uagb-slider-child-wrap swiper-slide uagb-block-191fb837\"><div class=\"swiper-content\"><style>.kb-image5782_42d0d2-59.kb-image-is-ratio-size, .kb-image5782_42d0d2-59 .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_42d0d2-59.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_42d0d2-59 .kb-image-is-ratio-size{align-self:unset;}.kb-image5782_42d0d2-59 figure{max-width:280px;}.kb-image5782_42d0d2-59 .image-is-svg, .kb-image5782_42d0d2-59 .image-is-svg img{width:100%;}.kb-image5782_42d0d2-59 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image5782_42d0d2-59 img.kb-img, .kb-image5782_42d0d2-59 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5782_42d0d2-59\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><a href=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_.webp\" class=\"kb-advanced-image-link\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_.webp\" alt=\"\" class=\"kb-img wp-image-6827\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_.webp 600w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_-300x300.webp 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_-150x150.webp 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_-12x12.webp 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/71YWyrw-ONL._AC_FMavif_UC231231_CACC231231_QL58_-80x80.webp 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"padding-top:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30)\">NAD+ de \u00f3tima qualidade, j\u00e1 experimentei alguns e este parece mais potente. Minha pele est\u00e1 muito melhor agora e continuarei a us\u00e1-lo!<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Rosa, \u2b50\u2b50\u2b50\u2b50\u2b50<\/p>\n<\/div><\/div>\n<\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile has-palette-color-6-color has-black-background-color has-text-color has-background has-link-color wp-elements-9a22e582b684bb4fdb35aaab506081c0\" style=\"border-radius:5px;grid-template-columns:auto 40%\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-palette-color-6-color has-text-color has-link-color wp-elements-1e5f702c3756207002d4b22c73866869\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);font-size:clamp(18.959px, 1.185rem + ((1vw - 3.2px) * 0.863), 30px);\">Amado pelos m\u00e9dicos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os neur\u00f4nios do c\u00e9rebro s\u00e3o as c\u00e9lulas do corpo que mais demandam energia. Ao aumentar suas reservas de NAD+, voc\u00ea pode manter um suprimento constante de energia e nutri\u00e7\u00e3o para o c\u00e9rebro, a fim de manter a qualidade do foco e do trabalho por mais tempo. Por outro lado, o caf\u00e9 n\u00e3o trata a principal causa da falta de foco ou da fadiga energ\u00e9tica e n\u00e3o aborda o metabolismo celular. Em vez disso, o caf\u00e9 oculta temporariamente a fadiga, causa quedas de energia e tamb\u00e9m cria depend\u00eancia, exigindo mais x\u00edcaras de caf\u00e9 para obter o mesmo foco.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/expert.png\" alt=\"\" class=\"wp-image-6829 size-full\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/expert.png 800w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/expert-300x300.png 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/expert-150x150.png 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/expert-768x768.png 768w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/expert-12x12.png 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/expert-80x80.png 80w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n<style>.kb-image5782_c65dc6-f6.kb-image-is-ratio-size, .kb-image5782_c65dc6-f6 .kb-image-is-ratio-size{max-width:400px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_c65dc6-f6.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image5782_c65dc6-f6 .kb-image-is-ratio-size{align-self:unset;}.kb-image5782_c65dc6-f6 figure{max-width:400px;}.kb-image5782_c65dc6-f6 .image-is-svg, .kb-image5782_c65dc6-f6 .image-is-svg img{width:100%;}.kb-image5782_c65dc6-f6 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-image5782_c65dc6-f6 img.kb-img, .kb-image5782_c65dc6-f6 .kb-img img{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}@media all and (max-width: 1024px){.kb-image5782_c65dc6-f6 .kb-image-has-overlay:after{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}}@media all and (max-width: 1024px){.kb-image5782_c65dc6-f6 img.kb-img, .kb-image5782_c65dc6-f6 .kb-img img{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}}@media all and (max-width: 767px){.kb-image5782_c65dc6-f6 .kb-image-has-overlay:after{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kb-image5782_c65dc6-f6 img.kb-img, .kb-image5782_c65dc6-f6 .kb-img img{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image5782_c65dc6-f6\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/uvp.png\" class=\"kb-advanced-image-link\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/uvp.png\" alt=\"\" class=\"kb-img wp-image-6839\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/uvp.png 800w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/uvp-300x300.png 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/uvp-150x150.png 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/uvp-768x768.png 768w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/uvp-12x12.png 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/uvp-80x80.png 80w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile has-palette-color-6-color has-black-background-color has-text-color has-background has-link-color wp-elements-2a2d7175dc3ae64e7799544a078463d6\" style=\"border-radius:5px;grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/stats.png\" alt=\"\" class=\"wp-image-6837 size-full\" srcset=\"https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/stats.png 800w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/stats-300x300.png 300w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/stats-150x150.png 150w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/stats-768x768.png 768w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/stats-12x12.png 12w, https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/stats-80x80.png 80w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-palette-color-6-color has-text-color has-link-color wp-elements-3269c3ac8ceabfa0f1468c82e72d910d\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);font-size:clamp(18.959px, 1.185rem + ((1vw - 3.2px) * 0.863), 30px);\">Melhor recupera\u00e7\u00e3o e envelhecimento saud\u00e1vel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O NAD+ \u00e9 um sinal comum para o reparo do DNA, pois liga as prote\u00ednas de reparo \u00e0s fitas de DNA danificadas. Isso permite que o corpo acelere seus processos naturais de reparo e deixe os tecidos rejuvenescidos e renovados. Esse processo de reparo diminui o tempo de recupera\u00e7\u00e3o ap\u00f3s a academia, reduz as dores nas articula\u00e7\u00f5es e nas costas e tamb\u00e9m contribui para um envelhecimento mais saud\u00e1vel ao longo do tempo.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-d212a429 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/hexibella.com\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 190.9V185.1C0 115.2 50.52 55.58 119.4 44.1C164.1 36.51 211.4 51.37 244 84.02L256 96L267.1 84.02C300.6 51.37 347 36.51 392.6 44.1C461.5 55.58 512 115.2 512 185.1V190.9C512 232.4 494.8 272.1 464.4 300.4L283.7 469.1C276.2 476.1 266.3 480 256 480C245.7 480 235.8 476.1 228.3 469.1L47.59 300.4C17.23 272.1 .0003 232.4 .0003 190.9L0 190.9z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Nossa garantia<\/h3><\/div><p class=\"uagb-ifb-desc\">Oferecemos uma pol\u00edtica de devolu\u00e7\u00e3o de 30 dias sem questionamentos para lhe dar tranquilidade em rela\u00e7\u00e3o \u00e0 sua compra. Se tiver alguma d\u00favida ou preocupa\u00e7\u00e3o, entre em contato com o suporte ao cliente pelo e-mail support@hexibella.com<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5c408e91\"><h2 class=\"uagb-heading-text\">Perguntas frequentes<\/h2><\/div>\n\n\n<div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-edb52445 uagb-faq-icon-row uagb-faq-layout-accordion uagb-faq-expand-first-false uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height\" data-faqtoggle=\"true\" role=\"tablist\"><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-898a77c6\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">O envio \u00e9 gratuito? Quanto tempo vai demorar?<\/span><\/div><div class=\"uagb-faq-content\"><p>Nossos custos de envio est\u00e3o inclu\u00eddos no pre\u00e7o e o envio leva de 5 a 9 dias \u00fateis para a maior parte do mundo. <\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-6349a889\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">Voc\u00eas t\u00eam uma garantia de devolu\u00e7\u00e3o do dinheiro?<\/span><\/div><div class=\"uagb-faq-content\"><p>Sim! Oferecemos devolu\u00e7\u00f5es gratuitas por 30 dias em todos os pedidos.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-8e3db11c\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">Minhas informa\u00e7\u00f5es de pagamento est\u00e3o seguras?<\/span><\/div><div class=\"uagb-faq-content\"><p>Suas informa\u00e7\u00f5es de pagamento s\u00e3o totalmente criptografadas e seguras. Usamos o Stripe e o PayPal para processar transa\u00e7\u00f5es e ambos os servi\u00e7os usam t\u00e9cnicas avan\u00e7adas de criptografia para garantir a seguran\u00e7a de suas informa\u00e7\u00f5es de pagamento.<\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-7229b0cf\" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\">Posso rastrear meu pedido?<\/span><\/div><div class=\"uagb-faq-content\"><p>Sim. Assim que o pedido for enviado, enviaremos um e-mail atualizando o status do seu pedido com um n\u00famero de rastreamento.<\/p><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p style=\"margin-bottom: 19px; margin-top: 0px; padding-top:0px; font-size:16px;\"><b><svg viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/star-svgrepo-com.svg\" width=\"22\" height=\"22\" style=\"vertical-align: -0.33em; margin-top:0px;\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"> <path d=\"M11.5245 3.46353C11.6741 3.00287 12.3259 3.00287 12.4755 3.46353L14.1329 8.56434C14.1998 8.77035 14.3918 8.90983 14.6084 8.90983H19.9717C20.4561 8.90983 20.6575 9.52964 20.2656 9.81434L15.9266 12.9668C15.7514 13.0941 15.678 13.3198 15.745 13.5258L17.4023 18.6266C17.552 19.0873 17.0248 19.4704 16.6329 19.1857L12.2939 16.0332C12.1186 15.9059 11.8814 15.9059 11.7061 16.0332L7.3671 19.1857C6.97524 19.4704 6.448 19.0873 6.59768 18.6266L8.25503 13.5258C8.32197 13.3198 8.24864 13.0941 8.07339 12.9668L3.73438 9.81434C3.34253 9.52964 3.54392 8.90983 4.02828 8.90983H9.39159C9.6082 8.90983 9.80018 8.77035 9.86712 8.56434L11.5245 3.46353Z\" fill=\"#000000\"><\/path> <\/g><\/svg><svg viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/star-svgrepo-com.svg\" width=\"22\" height=\"22\" style=\"vertical-align: -0.33em; margin-top:0px;\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"> <path d=\"M11.5245 3.46353C11.6741 3.00287 12.3259 3.00287 12.4755 3.46353L14.1329 8.56434C14.1998 8.77035 14.3918 8.90983 14.6084 8.90983H19.9717C20.4561 8.90983 20.6575 9.52964 20.2656 9.81434L15.9266 12.9668C15.7514 13.0941 15.678 13.3198 15.745 13.5258L17.4023 18.6266C17.552 19.0873 17.0248 19.4704 16.6329 19.1857L12.2939 16.0332C12.1186 15.9059 11.8814 15.9059 11.7061 16.0332L7.3671 19.1857C6.97524 19.4704 6.448 19.0873 6.59768 18.6266L8.25503 13.5258C8.32197 13.3198 8.24864 13.0941 8.07339 12.9668L3.73438 9.81434C3.34253 9.52964 3.54392 8.90983 4.02828 8.90983H9.39159C9.6082 8.90983 9.80018 8.77035 9.86712 8.56434L11.5245 3.46353Z\" fill=\"#000000\"><\/path> <\/g><\/svg><svg viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/star-svgrepo-com.svg\" width=\"22\" height=\"22\" style=\"vertical-align: -0.33em; margin-top:0px;\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"> <path d=\"M11.5245 3.46353C11.6741 3.00287 12.3259 3.00287 12.4755 3.46353L14.1329 8.56434C14.1998 8.77035 14.3918 8.90983 14.6084 8.90983H19.9717C20.4561 8.90983 20.6575 9.52964 20.2656 9.81434L15.9266 12.9668C15.7514 13.0941 15.678 13.3198 15.745 13.5258L17.4023 18.6266C17.552 19.0873 17.0248 19.4704 16.6329 19.1857L12.2939 16.0332C12.1186 15.9059 11.8814 15.9059 11.7061 16.0332L7.3671 19.1857C6.97524 19.4704 6.448 19.0873 6.59768 18.6266L8.25503 13.5258C8.32197 13.3198 8.24864 13.0941 8.07339 12.9668L3.73438 9.81434C3.34253 9.52964 3.54392 8.90983 4.02828 8.90983H9.39159C9.6082 8.90983 9.80018 8.77035 9.86712 8.56434L11.5245 3.46353Z\" fill=\"#000000\"><\/path> <\/g><\/svg><svg viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/star-svgrepo-com.svg\" width=\"22\" height=\"22\" style=\"vertical-align: -0.33em; margin-top:0px;\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"> <path d=\"M11.5245 3.46353C11.6741 3.00287 12.3259 3.00287 12.4755 3.46353L14.1329 8.56434C14.1998 8.77035 14.3918 8.90983 14.6084 8.90983H19.9717C20.4561 8.90983 20.6575 9.52964 20.2656 9.81434L15.9266 12.9668C15.7514 13.0941 15.678 13.3198 15.745 13.5258L17.4023 18.6266C17.552 19.0873 17.0248 19.4704 16.6329 19.1857L12.2939 16.0332C12.1186 15.9059 11.8814 15.9059 11.7061 16.0332L7.3671 19.1857C6.97524 19.4704 6.448 19.0873 6.59768 18.6266L8.25503 13.5258C8.32197 13.3198 8.24864 13.0941 8.07339 12.9668L3.73438 9.81434C3.34253 9.52964 3.54392 8.90983 4.02828 8.90983H9.39159C9.6082 8.90983 9.80018 8.77035 9.86712 8.56434L11.5245 3.46353Z\" fill=\"#000000\"><\/path> <\/g><\/svg><svg viewbox=\"0 0 24 24\" fill=\"none\" xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/star-svgrepo-com.svg\" width=\"22\" height=\"22\" style=\"vertical-align: -0.33em; margin-top:0px;\"><g id=\"SVGRepo_bgCarrier\" stroke-width=\"0\"><\/g><g id=\"SVGRepo_tracerCarrier\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/g><g id=\"SVGRepo_iconCarrier\"> <path d=\"M11.5245 3.46353C11.6741 3.00287 12.3259 3.00287 12.4755 3.46353L14.1329 8.56434C14.1998 8.77035 14.3918 8.90983 14.6084 8.90983H19.9717C20.4561 8.90983 20.6575 9.52964 20.2656 9.81434L15.9266 12.9668C15.7514 13.0941 15.678 13.3198 15.745 13.5258L17.4023 18.6266C17.552 19.0873 17.0248 19.4704 16.6329 19.1857L12.2939 16.0332C12.1186 15.9059 11.8814 15.9059 11.7061 16.0332L7.3671 19.1857C6.97524 19.4704 6.448 19.0873 6.59768 18.6266L8.25503 13.5258C8.32197 13.3198 8.24864 13.0941 8.07339 12.9668L3.73438 9.81434C3.34253 9.52964 3.54392 8.90983 4.02828 8.90983H9.39159C9.6082 8.90983 9.80018 8.77035 9.86712 8.56434L11.5245 3.46353Z\" fill=\"#000000\"><\/path> <\/g><\/svg> 4,86 \/ 5 (328 avalia\u00e7\u00f5es)<\/b><\/p>\n<p style=\"font-size:15px;\"><svg xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/icons8-checkmark.svg\" x=\"0px\" y=\"0px\" width=\"20\" height=\"20\" style=\"vertical-align: -0.33em\" viewbox=\"0 0 64 64\">\n<path d=\"M32,6C17.641,6,6,17.641,6,32c0,14.359,11.641,26,26,26s26-11.641,26-26C58,17.641,46.359,6,32,6z M29,42L18,31l2-3l9,6 l13.957-12L46,25L29,42z\"><\/path>\n<\/svg> <b>NAD+ Catakor da Hexibella Biolabs<\/b> <br \/>\n<svg xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/icons8-checkmark.svg\" x=\"0px\" y=\"0px\" width=\"20\" height=\"20\" style=\"vertical-align: -0.33em\" viewbox=\"0 0 64 64\">\n<path d=\"M32,6C17.641,6,6,17.641,6,32c0,14.359,11.641,26,26,26s26-11.641,26-26C58,17.641,46.359,6,32,6z M29,42L18,31l2-3l9,6 l13.957-12L46,25L29,42z\"><\/path>\n<\/svg> Foco aprimorado, mais energia e melhor humor<br \/>\n<svg xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/icons8-checkmark.svg\" x=\"0px\" y=\"0px\" width=\"20\" height=\"20\" style=\"vertical-align: -0.33em\" viewbox=\"0 0 64 64\">\n<path d=\"M32,6C17.641,6,6,17.641,6,32c0,14.359,11.641,26,26,26s26-11.641,26-26C58,17.641,46.359,6,32,6z M29,42L18,31l2-3l9,6 l13.957-12L46,25L29,42z\"><\/path>\n<\/svg> NAD+ lipossomal = Absor\u00e7\u00e3o 9 vezes melhor<br \/>\n<svg xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/icons8-checkmark.svg\" x=\"0px\" y=\"0px\" width=\"20\" height=\"20\" style=\"vertical-align: -0.33em\" viewbox=\"0 0 64 64\">\n<path d=\"M32,6C17.641,6,6,17.641,6,32c0,14.359,11.641,26,26,26s26-11.641,26-26C58,17.641,46.359,6,32,6z M29,42L18,31l2-3l9,6 l13.957-12L46,25L29,42z\"><\/path>\n<\/svg> Tomar 1-2 c\u00e1psulas por dia<br \/>\n<svg xmlns=\"https:\/\/hexibella.com\/\/www.hexibella.com\/wp-content\/uploads\/2024\/11\/icons8-checkmark.svg\" x=\"0px\" y=\"0px\" width=\"20\" height=\"20\" style=\"vertical-align: -0.33em\" viewbox=\"0 0 64 64\">\n<path d=\"M32,6C17.641,6,6,17.641,6,32c0,14.359,11.641,26,26,26s26-11.641,26-26C58,17.641,46.359,6,32,6z M29,42L18,31l2-3l9,6 l13.957-12L46,25L29,42z\"><\/path>\n<\/svg> O pre\u00e7o inclui o IVA e os custos de envio<\/p>\n<div style=\"border: 1px solid black; padding: 10px; display: flex; align-items: center; justify-content: space-between; border-radius: 11px; height: 81px; line-height: 1; background-color:#000000;\">\n<div style=\"flex: 0 0 auto; display: flex; align-items: center; background-color:#000000;\"><img decoding=\"async\" style=\"width: 60px; height: 60px; border-radius: 6px;\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2025\/09\/en-mockup-150x150.png\" alt=\"Soro de Hexibella\" \/><\/div>\n<div style=\"flex: 1; padding-left: 10px; text-align: left; display: flex; align-items: center;\">\n<p style=\"margin: 0; font-weight: bold; font-size: 14px; color:#FFFFFF;\">Compre 1 e ganhe 1 gr\u00e1tis (2 meses de suprimento no total)<\/p>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"featured_media":6828,"template":"","meta":{"_acf_changed":false,"bwfblock_default_font":"","_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[143],"product_tag":[],"class_list":["post-5782","product","type-product","status-publish","has-post-thumbnail","product_cat-health","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup.png",800,800,false],"thumbnail":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-150x150.png",150,150,true],"medium":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-300x300.png",300,300,true],"medium_large":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-768x768.png",768,768,true],"large":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup.png",800,800,false],"1536x1536":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup.png",800,800,false],"2048x2048":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup.png",800,800,false],"trp-custom-language-flag":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-12x12.png",12,12,true],"woocommerce_archive_thumbnail":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-300x300.png",300,300,true],"woocommerce_thumbnail":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-300x300.png",300,300,true],"woocommerce_single":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup.png",800,800,false],"woocommerce_gallery_thumbnail":["https:\/\/hexibella-modehaus.de\/wp-content\/uploads\/2025\/09\/en-mockup-80x80.png",80,80,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/hexibella-modehaus.de\/pt\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"4.86 \/ 5 (328 Reviews) NAD+ Catakor By Hexibella Biolabs Improved Focus, More Energy, & Better Mood Liposomal NAD+ = 9x Better Absorption Take 1-2 Capsules Per Day Price Includes VAT And Shipping Costs Buy 1, Get 1 Free (2 Months Supply In Total)","_links":{"self":[{"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/product\/5782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/media\/6828"}],"wp:attachment":[{"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/media?parent=5782"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/product_brand?post=5782"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/product_cat?post=5782"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hexibella-modehaus.de\/pt\/wp-json\/wp\/v2\/product_tag?post=5782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}